{"id":4985,"date":"2026-01-27T14:19:00","date_gmt":"2026-01-27T14:19:00","guid":{"rendered":"https:\/\/mpr-labs.com\/?p=4985"},"modified":"2026-02-25T10:47:22","modified_gmt":"2026-02-25T10:47:22","slug":"lacqua-nei-cosmetici-e-sempre-necessaria","status":"publish","type":"post","link":"https:\/\/mpr-labs.com\/it\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/","title":{"rendered":"Acqua nei cosmetici: \u00e8 sempre necessaria?"},"content":{"rendered":"<p><strong>L'acqua \u00e8 una delle materie prime pi\u00f9 utilizzate nelle formulazioni cosmetiche ed \u00e8 il principale ingrediente quantitativo di molti prodotti.<\/strong> Tuttavia, la sua presenza nella formulazione \u00e8 talvolta data per scontata, anche se, da un punto di vista tecnologico, il suo utilizzo dovrebbe sempre essere una decisione formulativa consapevole. Questo articolo discute <strong>il ruolo dell'acqua nei cosmetici<\/strong>, le sue funzioni tecnologiche, i requisiti di qualit\u00e0 e le situazioni in cui \u00e8 possibile - e talvolta giustificato - creare formulazioni anidre.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_81 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice dei contenuti:<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a03fa3785c6b\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #dd9933;color:#dd9933\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #dd9933;color:#dd9933\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a03fa3785c6b\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/mpr-labs.com\/it\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#Rola_wody_w_formulacjach_kosmetycznych\" >Il ruolo dell'acqua nelle formulazioni cosmetiche<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/mpr-labs.com\/it\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#Woda_wplywa_rowniez_na\" >Anche l'acqua influisce:<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/mpr-labs.com\/it\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#Woda_a_emulsje_i_inne_uklady_kosmetyczne\" >Acqua contro emulsioni e altri sistemi cosmetici<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/mpr-labs.com\/it\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#Jakosc_wody_stosowanej_w_kosmetykach\" >Qualit\u00e0 dell'acqua utilizzata nei cosmetici<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/mpr-labs.com\/it\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#Woda_a_bezpieczenstwo_mikrobiologiczne\" >Acqua e sicurezza microbiologica<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/mpr-labs.com\/it\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#Czy_woda_jest_zawsze_potrzebna\" >L'acqua \u00e8 sempre necessaria?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/mpr-labs.com\/it\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#Woda_a_deklaracje_marketingowe\" >Acqua e dichiarazioni di marketing<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/mpr-labs.com\/it\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#Rola_laboratorium_R_D_w_decyzji_o_zastosowaniu_wody\" >Il ruolo del laboratorio di R&amp;S nella decisione di utilizzare l'acqua<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/mpr-labs.com\/it\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#Podsumowanie\" >Sintesi<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Rola_wody_w_formulacjach_kosmetycznych\"><\/span><strong>Il ruolo dell'acqua nelle formulazioni cosmetiche<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>L'acqua nei cosmetici<\/strong> ha principalmente la funzione di <strong>solvente<\/strong> e <strong>vettore di sostanze attive<\/strong>. Permette di sciogliere ingredienti idrofili come umettanti, sali, alcune vitamine o estratti vegetali. Ci\u00f2 consente agli ingredienti attivi di essere distribuiti uniformemente nel prodotto e di raggiungere efficacemente la superficie cutanea.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Woda_wplywa_rowniez_na\"><\/span>Anche l'acqua influisce:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la consistenza e la reologia del prodotto,<\/li>\n\n\n\n<li>facilit\u00e0 di applicazione e distribuzione,<\/li>\n\n\n\n<li>sensazioni sensoriali durante l'applicazione.<\/li>\n<\/ul>\n\n\n\n<p>Tuttavia, va sottolineato che <strong>l'acqua stessa non \u00e8 un ingrediente attivo<\/strong> e non fornisce un'idratazione cutanea a lungo termine. L'effetto di cura della pelle delle formulazioni acquose dipende dalla presenza di umettanti ben selezionati, sostanze occlusive e ingredienti che supportano la barriera epidermica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Woda_a_emulsje_i_inne_uklady_kosmetyczne\"><\/span><strong>Acqua contro emulsioni e altri sistemi cosmetici<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>Nei cosmetici, l'acqua \u00e8 pi\u00f9 comunemente presente in:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Emulsioni O\/W o W\/O,<\/li>\n\n\n\n<li>soluzioni acquose (ad es. tonici),<\/li>\n\n\n\n<li>idrogeli.<\/li>\n<\/ul>\n\n\n\n<p>Nel caso delle emulsioni, l'acqua \u00e8 una delle fasi, ma l'acqua \u00e8 una delle fasi. <strong>non agisce come emulsionante<\/strong>. La stabilit\u00e0 del sistema di emulsione \u00e8 garantita da emulsionanti e stabilizzatori opportunamente selezionati, mentre l'acqua influenza la viscosit\u00e0, la spalmabilit\u00e0 e le propriet\u00e0 funzionali del prodotto. La sua quantit\u00e0 e qualit\u00e0 hanno un impatto diretto sulla stabilit\u00e0 fisico-chimica della formulazione.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Jakosc_wody_stosowanej_w_kosmetykach\"><\/span><strong>Qualit\u00e0 dell'acqua utilizzata nei cosmetici<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Dal punto di vista di <a href=\"https:\/\/mpr-labs.com\">laboratorio cosmetico<\/a> L'acqua \u00e8 una materia prima che richiede un controllo speciale. L'acqua utilizzata nella produzione di cosmetici deve rispondere a requisiti rigorosi <strong>purezza chimica e microbiologica<\/strong>, in conformit\u00e0 ai principi delle buone pratiche di fabbricazione (GMP).<\/p>\n\n\n\n<p>Le pratiche includono:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>acqua purificata,<\/li>\n\n\n\n<li>acqua demineralizzata,<\/li>\n\n\n\n<li>acqua ad osmosi inversa.<\/li>\n<\/ul>\n\n\n\n<p>I processi di trattamento comprendono la filtrazione, l'osmosi inversa, la disinfezione (ad es. UV) e il regolare monitoraggio microbiologico (controllare la <a href=\"https:\/\/mpr-labs.com\/badania-mikrobiologiczne\/\">test microbiologici<\/a>). Una qualit\u00e0 dell'acqua inadeguata pu\u00f2 portare a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>instabilit\u00e0 del prodotto,<\/li>\n\n\n\n<li>crescita microbica,<\/li>\n\n\n\n<li>riduzione della durata di vita,<\/li>\n\n\n\n<li>rischi per la sicurezza dei consumatori.<\/li>\n<\/ul>\n\n\n\n<p>Pertanto, l'acqua non pu\u00f2 essere considerata un ingrediente \u201eneutro\u201d o \u201einerte\u201d in una ricetta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Woda_a_bezpieczenstwo_mikrobiologiczne\"><\/span><strong>Acqua e sicurezza microbiologica<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La presenza di acqua in un cosmetico crea condizioni che favoriscono la crescita di microrganismi. Pertanto, le formulazioni acquose <strong>richiedono sempre un sistema di manutenzione efficace<\/strong>, abbinato a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>pH del prodotto,<\/li>\n\n\n\n<li>tipo di imballaggio,<\/li>\n\n\n\n<li>l'uso previsto,<\/li>\n\n\n\n<li>gruppo target di consumatori.<\/li>\n<\/ul>\n\n\n\n<p>Il sistema conservante \u00e8 parte integrante della valutazione della sicurezza del cosmetico e deve garantire la protezione microbiologica per tutta la durata di conservazione dichiarata del prodotto. La decisione di utilizzare l'acqua nella formulazione \u00e8 quindi direttamente collegata a ulteriori requisiti di stabilit\u00e0 e di test microbiologici.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Czy_woda_jest_zawsze_potrzebna\"><\/span><strong>L'acqua \u00e8 sempre necessaria?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Anche se l'acqua \u00e8 ampiamente utilizzata, <strong>non \u00e8 sempre necessario<\/strong>. Negli ultimi anni si \u00e8 assistito a un crescente interesse per le formulazioni anidre (anhydrous), utilizzate, tra l'altro, in:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>oli e lozioni,<\/li>\n\n\n\n<li>unguenti,<\/li>\n\n\n\n<li>bastoni,<\/li>\n\n\n\n<li>polveri,<\/li>\n\n\n\n<li>sieri concentrati.<\/li>\n<\/ul>\n\n\n\n<p>I cosmetici senza acqua sono caratterizzati da:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>un rischio microbiologico inferiore,<\/li>\n\n\n\n<li>spesso senza bisogno di conservanti,<\/li>\n\n\n\n<li>alta concentrazione di principi attivi,<\/li>\n\n\n\n<li>buona stabilit\u00e0 fisica e chimica - controllo <a href=\"https:\/\/mpr-labs.com\/badania-fizykochemiczne\/\">test fisico-chimici<\/a>.<\/li>\n<\/ul>\n\n\n\n<p>Per la pelle secca o sensibile, le formulazioni anidre sono talvolta meglio tollerate, soprattutto se contengono ingredienti che supportano la barriera lipidica epidermica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Woda_a_deklaracje_marketingowe\"><\/span><strong>Acqua e dichiarazioni di marketing<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Nel contesto della comunicazione di mercato <strong>l'acqua \u00e8 talvolta considerata un ingrediente \u201emeno prezioso\u201d o \u201eriempitivo\u201d.\u201d<\/strong>. Questo approccio non riflette il ruolo reale dell'acqua nelle formulazioni cosmetiche. Da un punto di vista tecnologico, l'acqua \u00e8 una materia prima funzionale e la sua presenza o assenza dovrebbe basarsi sullo scopo del prodotto e non solo sulle aspettative del marketing.<\/p>\n\n\n\n<p>Una comunicazione efficace deve tenere conto del fatto che:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L'acqua \u00e8 essenziale in molti tipi di formulazione,<\/li>\n\n\n\n<li>la sua qualit\u00e0 \u00e8 fondamentale per la sicurezza,<\/li>\n\n\n\n<li>L'assenza di acqua non significa automaticamente una maggiore efficacia del prodotto.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Rola_laboratorium_R_D_w_decyzji_o_zastosowaniu_wody\"><\/span><strong>Il ruolo del laboratorio di R&amp;S nella decisione di utilizzare l'acqua<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Il laboratorio responsabile della formulazione deve valutare l'adeguatezza dell'uso dell'acqua nel contesto:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Caratteristiche del prodotto,<\/li>\n\n\n\n<li>profilo utente,<\/li>\n\n\n\n<li>stabilit\u00e0 e sostenibilit\u00e0,<\/li>\n\n\n\n<li>sicurezza microbiologica,<\/li>\n\n\n\n<li>compatibilit\u00e0 con l'imballaggio.<\/li>\n<\/ul>\n\n\n\n<p>La decisione di utilizzare una formulazione acquosa o anidra deve essere il risultato di un'analisi tecnologica e di una valutazione del rischio, non delle tendenze del mercato.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Podsumowanie\"><\/span><strong>Sintesi<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>L'acqua \u00e8 una delle materie prime fondamentali per i cosmetici, ma la sua presenza non deve essere trattata come uno standard che richiede un'applicazione irriflessa. Dal punto di vista del laboratorio, l'acqua \u00e8 un ingrediente funzionale che:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>influisce sulla stabilit\u00e0 e sulla sicurezza del prodotto,<\/li>\n\n\n\n<li>determina la necessit\u00e0 di manutenzione,<\/li>\n\n\n\n<li>influisce sulle prestazioni del cosmetico.<\/li>\n<\/ul>\n\n\n\n<p>La risposta alla domanda \u201el'acqua \u00e8 sempre necessaria?\u201d \u00e8: <strong>non sempre<\/strong>. Il suo utilizzo deve essere una decisione di formulazione consapevole, basata sulle conoscenze tecnologiche, sui requisiti di sicurezza e sulla funzione target del prodotto.<\/p>","protected":false},"excerpt":{"rendered":"<p>Woda jest jednym z najcz\u0119\u015bciej stosowanych surowc\u00f3w w formulacjach kosmetycznych i w wielu produktach stanowi ich g\u0142\u00f3wny sk\u0142adnik ilo\u015bciowy. Jej obecno\u015b\u0107 w recepturze bywa jednak traktowana jako oczywista, mimo \u017ce z technologicznego punktu widzenia jej zastosowanie zawsze powinno by\u0107 \u015bwiadom\u0105 decyzj\u0105 formulacyjn\u0105. W niniejszym artykule om\u00f3wiono rol\u0119 wody w kosmetykach, jej funkcje technologiczne, wymagania jako\u015bciowe [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4987,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-4985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Woda w kosmetyku - czy zawsze jest potrzebna? - MPR Labs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mpr-labs.com\/it\/lacqua-nei-cosmetici-e-sempre-necessaria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Woda w kosmetyku - czy zawsze jest potrzebna? - MPR Labs\" \/>\n<meta property=\"og:description\" content=\"Woda jest jednym z najcz\u0119\u015bciej stosowanych surowc\u00f3w w formulacjach kosmetycznych i w wielu produktach stanowi ich g\u0142\u00f3wny sk\u0142adnik ilo\u015bciowy. Jej obecno\u015b\u0107 w recepturze bywa jednak traktowana jako oczywista, mimo \u017ce z technologicznego punktu widzenia jej zastosowanie zawsze powinno by\u0107 \u015bwiadom\u0105 decyzj\u0105 formulacyjn\u0105. W niniejszym artykule om\u00f3wiono rol\u0119 wody w kosmetykach, jej funkcje technologiczne, wymagania jako\u015bciowe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mpr-labs.com\/it\/lacqua-nei-cosmetici-e-sempre-necessaria\/\" \/>\n<meta property=\"og:site_name\" content=\"MPR Labs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MPRLabs\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-27T14:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T10:47:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mpr-labs.com\/wp-content\/uploads\/2026\/02\/woda-w-kosmetykach.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1408\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"\u0141ukasz Miernik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0141ukasz Miernik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/\"},\"author\":{\"name\":\"\u0141ukasz Miernik\",\"@id\":\"https:\/\/mpr-labs.com\/#\/schema\/person\/e6262bfc4e94a16ae3e1847195335ed4\"},\"headline\":\"Woda w kosmetyku &#8211; czy zawsze jest potrzebna?\",\"datePublished\":\"2026-01-27T14:19:00+00:00\",\"dateModified\":\"2026-02-25T10:47:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/\"},\"wordCount\":829,\"publisher\":{\"@id\":\"https:\/\/mpr-labs.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mpr-labs.com\/wp-content\/uploads\/2026\/02\/woda-w-kosmetykach.png\",\"articleSection\":[\"Informacje\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/\",\"url\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/\",\"name\":\"Woda w kosmetyku - czy zawsze jest potrzebna? - MPR Labs\",\"isPartOf\":{\"@id\":\"https:\/\/mpr-labs.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mpr-labs.com\/wp-content\/uploads\/2026\/02\/woda-w-kosmetykach.png\",\"datePublished\":\"2026-01-27T14:19:00+00:00\",\"dateModified\":\"2026-02-25T10:47:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#primaryimage\",\"url\":\"https:\/\/mpr-labs.com\/wp-content\/uploads\/2026\/02\/woda-w-kosmetykach.png\",\"contentUrl\":\"https:\/\/mpr-labs.com\/wp-content\/uploads\/2026\/02\/woda-w-kosmetykach.png\",\"width\":1408,\"height\":768,\"caption\":\"woda w kosmetykach czy zawsze jest potrzebna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/mpr-labs.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Woda w kosmetyku &#8211; czy zawsze jest potrzebna?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mpr-labs.com\/#website\",\"url\":\"https:\/\/mpr-labs.com\/\",\"name\":\"MPR Labs\",\"description\":\"MPR Labs - Laboratorium Kosmetyczne\",\"publisher\":{\"@id\":\"https:\/\/mpr-labs.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mpr-labs.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mpr-labs.com\/#organization\",\"name\":\"MPR Labs Sp. z o.o.\",\"alternateName\":\"MPR Labs\",\"url\":\"https:\/\/mpr-labs.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/mpr-labs.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mpr-labs.com\/wp-content\/uploads\/2023\/05\/logo-new.png\",\"contentUrl\":\"https:\/\/mpr-labs.com\/wp-content\/uploads\/2023\/05\/logo-new.png\",\"width\":1150,\"height\":328,\"caption\":\"MPR Labs Sp. z o.o.\"},\"image\":{\"@id\":\"https:\/\/mpr-labs.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MPRLabs\",\"https:\/\/www.linkedin.com\/company\/mpr-labs\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/mpr-labs.com\/#\/schema\/person\/e6262bfc4e94a16ae3e1847195335ed4\",\"name\":\"\u0141ukasz Miernik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/mpr-labs.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e4995c56590bbebda64195f8844faa71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e4995c56590bbebda64195f8844faa71?s=96&d=mm&r=g\",\"caption\":\"\u0141ukasz Miernik\"},\"sameAs\":[\"https:\/\/mpr-labs.com\/\"],\"url\":\"https:\/\/mpr-labs.com\/it\/author\/l-miernik\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acqua nei cosmetici: \u00e8 sempre necessaria? - Laboratori MPR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mpr-labs.com\/it\/lacqua-nei-cosmetici-e-sempre-necessaria\/","og_locale":"it_IT","og_type":"article","og_title":"Woda w kosmetyku - czy zawsze jest potrzebna? - MPR Labs","og_description":"Woda jest jednym z najcz\u0119\u015bciej stosowanych surowc\u00f3w w formulacjach kosmetycznych i w wielu produktach stanowi ich g\u0142\u00f3wny sk\u0142adnik ilo\u015bciowy. Jej obecno\u015b\u0107 w recepturze bywa jednak traktowana jako oczywista, mimo \u017ce z technologicznego punktu widzenia jej zastosowanie zawsze powinno by\u0107 \u015bwiadom\u0105 decyzj\u0105 formulacyjn\u0105. W niniejszym artykule om\u00f3wiono rol\u0119 wody w kosmetykach, jej funkcje technologiczne, wymagania jako\u015bciowe [&hellip;]","og_url":"https:\/\/mpr-labs.com\/it\/lacqua-nei-cosmetici-e-sempre-necessaria\/","og_site_name":"MPR Labs","article_publisher":"https:\/\/www.facebook.com\/MPRLabs","article_published_time":"2026-01-27T14:19:00+00:00","article_modified_time":"2026-02-25T10:47:22+00:00","og_image":[{"width":1408,"height":768,"url":"https:\/\/mpr-labs.com\/wp-content\/uploads\/2026\/02\/woda-w-kosmetykach.png","type":"image\/png"}],"author":"\u0141ukasz Miernik","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"\u0141ukasz Miernik","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#article","isPartOf":{"@id":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/"},"author":{"name":"\u0141ukasz Miernik","@id":"https:\/\/mpr-labs.com\/#\/schema\/person\/e6262bfc4e94a16ae3e1847195335ed4"},"headline":"Woda w kosmetyku &#8211; czy zawsze jest potrzebna?","datePublished":"2026-01-27T14:19:00+00:00","dateModified":"2026-02-25T10:47:22+00:00","mainEntityOfPage":{"@id":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/"},"wordCount":829,"publisher":{"@id":"https:\/\/mpr-labs.com\/#organization"},"image":{"@id":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#primaryimage"},"thumbnailUrl":"https:\/\/mpr-labs.com\/wp-content\/uploads\/2026\/02\/woda-w-kosmetykach.png","articleSection":["Informacje"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/","url":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/","name":"Acqua nei cosmetici: \u00e8 sempre necessaria? - Laboratori MPR","isPartOf":{"@id":"https:\/\/mpr-labs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#primaryimage"},"image":{"@id":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#primaryimage"},"thumbnailUrl":"https:\/\/mpr-labs.com\/wp-content\/uploads\/2026\/02\/woda-w-kosmetykach.png","datePublished":"2026-01-27T14:19:00+00:00","dateModified":"2026-02-25T10:47:22+00:00","breadcrumb":{"@id":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#primaryimage","url":"https:\/\/mpr-labs.com\/wp-content\/uploads\/2026\/02\/woda-w-kosmetykach.png","contentUrl":"https:\/\/mpr-labs.com\/wp-content\/uploads\/2026\/02\/woda-w-kosmetykach.png","width":1408,"height":768,"caption":"woda w kosmetykach czy zawsze jest potrzebna"},{"@type":"BreadcrumbList","@id":"https:\/\/mpr-labs.com\/woda-w-kosmetyku-czy-zawsze-jest-potrzebna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/mpr-labs.com\/"},{"@type":"ListItem","position":2,"name":"Woda w kosmetyku &#8211; czy zawsze jest potrzebna?"}]},{"@type":"WebSite","@id":"https:\/\/mpr-labs.com\/#website","url":"https:\/\/mpr-labs.com\/","name":"Laboratori MPR","description":"Laboratori MPR - Laboratorio di cosmetica","publisher":{"@id":"https:\/\/mpr-labs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mpr-labs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mpr-labs.com\/#organization","name":"MPR Labs Sp. z o.o.","alternateName":"MPR Labs","url":"https:\/\/mpr-labs.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mpr-labs.com\/#\/schema\/logo\/image\/","url":"https:\/\/mpr-labs.com\/wp-content\/uploads\/2023\/05\/logo-new.png","contentUrl":"https:\/\/mpr-labs.com\/wp-content\/uploads\/2023\/05\/logo-new.png","width":1150,"height":328,"caption":"MPR Labs Sp. z o.o."},"image":{"@id":"https:\/\/mpr-labs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MPRLabs","https:\/\/www.linkedin.com\/company\/mpr-labs\/"]},{"@type":"Person","@id":"https:\/\/mpr-labs.com\/#\/schema\/person\/e6262bfc4e94a16ae3e1847195335ed4","name":"\u0141ukasz Miernik","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mpr-labs.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e4995c56590bbebda64195f8844faa71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4995c56590bbebda64195f8844faa71?s=96&d=mm&r=g","caption":"\u0141ukasz Miernik"},"sameAs":["https:\/\/mpr-labs.com\/"],"url":"https:\/\/mpr-labs.com\/it\/author\/l-miernik\/"}]}},"_links":{"self":[{"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/posts\/4985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/comments?post=4985"}],"version-history":[{"count":2,"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/posts\/4985\/revisions"}],"predecessor-version":[{"id":4989,"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/posts\/4985\/revisions\/4989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/media\/4987"}],"wp:attachment":[{"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/media?parent=4985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/categories?post=4985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mpr-labs.com\/it\/wp-json\/wp\/v2\/tags?post=4985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}